{"id":67409,"date":"2024-10-07T16:29:13","date_gmt":"2024-10-07T14:29:13","guid":{"rendered":"https:\/\/vistiendobebes.com\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/"},"modified":"2026-02-02T09:59:09","modified_gmt":"2026-02-02T08:59:09","slug":"vestiti-autunnali-per-bambini-dolcezza-e-segretezza","status":"publish","type":"post","link":"https:\/\/vistiendobebes.com\/it\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/","title":{"rendered":"Vestiti autunnali per bambini: dulzura e secreto"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]<\/p>\r\n\r\n<p>La stagione autunno-inverno \u00e8 arrivata e da Juliana vi presentiamo due nuove collezioni che vestono i pi\u00f9 piccoli con morbidezza e fascino<!--more--><\/p>\r\n<p>Dolcezza e segreto. Queste collezioni di abiti autunnali per bambini sono progettate per tenere i bambini al caldo mentre si godono le avventure autunnali con stile. Ogni capo \u00e8 attentamente studiato per garantire comfort senza rinunciare all&#8217;eleganza che caratterizza Juliana.<\/p>\r\n<h2>Collezione Dulzura: capi morbidi e adorabili<\/h2>\r\n<p>La collezione Dulzura \u00e8 perfetta per chi cerca capi pieni di tenerezza e stile. Con delicati toni bianchi e realizzato in morbida maglia, ogni set \u00e8 ideale per le giornate pi\u00f9 fresche dell&#8217;autunno. Questa collezione \u00e8 composta da tutine, leggings, cappellini e coperte per i pi\u00f9 piccoli.<\/p>\r\n<p>Tra i pezzi pi\u00f9 affascinanti c&#8217;\u00e8 il set ghetta e cappello, un classico Juliana che unisce l&#8217;eleganza al calore e alla morbidezza della maglieria. Perfetto per eventi o passeggiate, questo e altri outfit autunnali per bambini sono un&#8217;opzione ideale per il tuo bambino. Abbiamo trovato anche questo morbido cappotto (rif. 24699), con un bordo in morbida pelliccia sul cappuccio, che lo rende ancora pi\u00f9 caldo e confortevole.<\/p>\r\n<p>Scopri di pi\u00f9 su questa accattivante collezione qui: <a href=\"https:\/\/vistiendobebes.com\/it\/portfolio\/collezione-dulzura\/\">Collezione Dulzura.<\/a><\/p>\r\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;66665,66657,66661&#8243; img_size=&#8221;medium&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]<\/p>\r\n<h3>Un design per celebrare l&#8217;eleganza dell&#8217;infanzia<\/h3>\r\n<p>La <strong>Collezione Secreto<\/strong> combina perfettamente raffinatezza e comfort, rendendo ogni capo una scelta ideale per eventi come battesimi, compleanni o feste di famiglia. Con un&#8217;attenzione particolare ai dettagli, i tessuti morbidi e le finiture raffinate spiccano in abiti, completi e accessori che ti faranno innamorare a prima vista.<\/p>\r\n<p>Quando vestiamo i nostri piccoli, non cerchiamo solo lo stile; vogliamo anche catturare quei ricordi indimenticabili che custodiremo per sempre. La <strong>Collezione Secreto<\/strong> \u00e8 molto pi\u00f9 di semplici abiti, \u00e8 un invito a celebrare l&#8217;infanzia con eleganza e autenticit\u00e0.<\/p>\r\n<p>Scopri la <strong>Collezione Secreto<\/strong> su <a href=\"https:\/\/vistiendobebes.com\/it\/portfolio\/collezione-secreto\/\" target=\"_new\" rel=\"noopener\">vistiendobebes.com<\/a> e rendi ogni occasione speciale un ricordo pieno di stile e tenerezza.<\/p>\r\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;66926,66938,66930&#8243; img_size=&#8221;medium&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row]<\/p>\r\n<p><\/p><\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;] La stagione autunno-inverno \u00e8 arrivata e da Juliana vi presentiamo due nuove collezioni che vestono i<\/p>\n","protected":false},"author":2,"featured_media":67417,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[422],"tags":[],"class_list":["post-67409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-moda-per-bambini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vestiti autunnali per bambini: dulzura e secreto - Juliana Vistiendo Beb\u00e9s<\/title>\n<meta name=\"description\" content=\"Scopri le collezioni Dulzura e Secreto di Juliana per la stagione autunno-inverno 24\/25. Vestiti per bambini per l&#039;autunno e l&#039;inverno.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vistiendobebes.com\/it\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vestiti autunnali per bambini: dulzura e secreto - Juliana Vistiendo Beb\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Scopri le collezioni Dulzura e Secreto di Juliana per la stagione autunno-inverno 24\/25. Vestiti per bambini per l&#039;autunno e l&#039;inverno.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vistiendobebes.com\/it\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/\" \/>\n<meta property=\"og:site_name\" content=\"Juliana Vistiendo Beb\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/julianavistiendobebes\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-07T14:29:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T08:59:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vistiendobebes.com\/wp-content\/uploads\/2024\/10\/abiti-autunnali-per-bambini.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1120\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Joaquin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaquin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\\\/\"},\"author\":{\"name\":\"Joaquin\",\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/#\\\/schema\\\/person\\\/76b9ff2be80bf0f4f9b7d41be6884e5c\"},\"headline\":\"Vestiti autunnali per bambini: dulzura e secreto\",\"datePublished\":\"2024-10-07T14:29:13+00:00\",\"dateModified\":\"2026-02-02T08:59:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\\\/\"},\"wordCount\":389,\"publisher\":{\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vistiendobebes.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/abiti-autunnali-per-bambini.png\",\"articleSection\":[\"moda per bambini\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\\\/\",\"url\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\\\/\",\"name\":\"Vestiti autunnali per bambini: dulzura e secreto - Juliana Vistiendo Beb\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vistiendobebes.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/abiti-autunnali-per-bambini.png\",\"datePublished\":\"2024-10-07T14:29:13+00:00\",\"dateModified\":\"2026-02-02T08:59:09+00:00\",\"description\":\"Scopri le collezioni Dulzura e Secreto di Juliana per la stagione autunno-inverno 24\\\/25. Vestiti per bambini per l'autunno e l'inverno.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vistiendobebes.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/abiti-autunnali-per-bambini.png\",\"contentUrl\":\"https:\\\/\\\/vistiendobebes.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/abiti-autunnali-per-bambini.png\",\"width\":1120,\"height\":550,\"caption\":\"abiti autunnali per bambini\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vestiti autunnali per bambini: dulzura e secreto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/\",\"name\":\"Juliana Vistiendo Beb\u00e9s\",\"description\":\"Marca de moda infantil\",\"publisher\":{\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/#organization\",\"name\":\"Juliana, Vistiendo Beb\u00e9s\",\"url\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vistiendobebes.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/marca-juliana.png\",\"contentUrl\":\"https:\\\/\\\/vistiendobebes.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/marca-juliana.png\",\"width\":909,\"height\":907,\"caption\":\"Juliana, Vistiendo Beb\u00e9s\"},\"image\":{\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/julianavistiendobebes\",\"https:\\\/\\\/www.instagram.com\\\/julianavistiendobebes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHaSPwnyKbcQ1Ppzf2roteA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vistiendobebes.com\\\/it\\\/#\\\/schema\\\/person\\\/76b9ff2be80bf0f4f9b7d41be6884e5c\",\"name\":\"Joaquin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8e28c816cd54ef531c1ecd2be4389ad63c838376f221db13621a179ef5cf57a0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8e28c816cd54ef531c1ecd2be4389ad63c838376f221db13621a179ef5cf57a0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8e28c816cd54ef531c1ecd2be4389ad63c838376f221db13621a179ef5cf57a0?s=96&d=mm&r=g\",\"caption\":\"Joaquin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vestiti autunnali per bambini: dulzura e secreto - Juliana Vistiendo Beb\u00e9s","description":"Scopri le collezioni Dulzura e Secreto di Juliana per la stagione autunno-inverno 24\/25. Vestiti per bambini per l'autunno e l'inverno.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vistiendobebes.com\/it\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/","og_locale":"it_IT","og_type":"article","og_title":"Vestiti autunnali per bambini: dulzura e secreto - Juliana Vistiendo Beb\u00e9s","og_description":"Scopri le collezioni Dulzura e Secreto di Juliana per la stagione autunno-inverno 24\/25. Vestiti per bambini per l'autunno e l'inverno.","og_url":"https:\/\/vistiendobebes.com\/it\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/","og_site_name":"Juliana Vistiendo Beb\u00e9s","article_publisher":"https:\/\/www.facebook.com\/julianavistiendobebes","article_published_time":"2024-10-07T14:29:13+00:00","article_modified_time":"2026-02-02T08:59:09+00:00","og_image":[{"width":1120,"height":550,"url":"https:\/\/vistiendobebes.com\/wp-content\/uploads\/2024\/10\/abiti-autunnali-per-bambini.png","type":"image\/png"}],"author":"Joaquin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Joaquin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vistiendobebes.com\/it\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/#article","isPartOf":{"@id":"https:\/\/vistiendobebes.com\/it\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/"},"author":{"name":"Joaquin","@id":"https:\/\/vistiendobebes.com\/it\/#\/schema\/person\/76b9ff2be80bf0f4f9b7d41be6884e5c"},"headline":"Vestiti autunnali per bambini: dulzura e secreto","datePublished":"2024-10-07T14:29:13+00:00","dateModified":"2026-02-02T08:59:09+00:00","mainEntityOfPage":{"@id":"https:\/\/vistiendobebes.com\/it\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/"},"wordCount":389,"publisher":{"@id":"https:\/\/vistiendobebes.com\/it\/#organization"},"image":{"@id":"https:\/\/vistiendobebes.com\/it\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/#primaryimage"},"thumbnailUrl":"https:\/\/vistiendobebes.com\/wp-content\/uploads\/2024\/10\/abiti-autunnali-per-bambini.png","articleSection":["moda per bambini"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/vistiendobebes.com\/it\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/","url":"https:\/\/vistiendobebes.com\/it\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/","name":"Vestiti autunnali per bambini: dulzura e secreto - Juliana Vistiendo Beb\u00e9s","isPartOf":{"@id":"https:\/\/vistiendobebes.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vistiendobebes.com\/it\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/#primaryimage"},"image":{"@id":"https:\/\/vistiendobebes.com\/it\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/#primaryimage"},"thumbnailUrl":"https:\/\/vistiendobebes.com\/wp-content\/uploads\/2024\/10\/abiti-autunnali-per-bambini.png","datePublished":"2024-10-07T14:29:13+00:00","dateModified":"2026-02-02T08:59:09+00:00","description":"Scopri le collezioni Dulzura e Secreto di Juliana per la stagione autunno-inverno 24\/25. Vestiti per bambini per l'autunno e l'inverno.","breadcrumb":{"@id":"https:\/\/vistiendobebes.com\/it\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vistiendobebes.com\/it\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vistiendobebes.com\/it\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/#primaryimage","url":"https:\/\/vistiendobebes.com\/wp-content\/uploads\/2024\/10\/abiti-autunnali-per-bambini.png","contentUrl":"https:\/\/vistiendobebes.com\/wp-content\/uploads\/2024\/10\/abiti-autunnali-per-bambini.png","width":1120,"height":550,"caption":"abiti autunnali per bambini"},{"@type":"BreadcrumbList","@id":"https:\/\/vistiendobebes.com\/it\/vestiti-autunnali-per-bambini-dolcezza-e-segretezza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vistiendobebes.com\/it\/"},{"@type":"ListItem","position":2,"name":"Vestiti autunnali per bambini: dulzura e secreto"}]},{"@type":"WebSite","@id":"https:\/\/vistiendobebes.com\/it\/#website","url":"https:\/\/vistiendobebes.com\/it\/","name":"Juliana Vistiendo Beb\u00e9s","description":"Marca de moda infantil","publisher":{"@id":"https:\/\/vistiendobebes.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vistiendobebes.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/vistiendobebes.com\/it\/#organization","name":"Juliana, Vistiendo Beb\u00e9s","url":"https:\/\/vistiendobebes.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vistiendobebes.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/vistiendobebes.com\/wp-content\/uploads\/2021\/07\/marca-juliana.png","contentUrl":"https:\/\/vistiendobebes.com\/wp-content\/uploads\/2021\/07\/marca-juliana.png","width":909,"height":907,"caption":"Juliana, Vistiendo Beb\u00e9s"},"image":{"@id":"https:\/\/vistiendobebes.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/julianavistiendobebes","https:\/\/www.instagram.com\/julianavistiendobebes\/","https:\/\/www.youtube.com\/channel\/UCHaSPwnyKbcQ1Ppzf2roteA"]},{"@type":"Person","@id":"https:\/\/vistiendobebes.com\/it\/#\/schema\/person\/76b9ff2be80bf0f4f9b7d41be6884e5c","name":"Joaquin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8e28c816cd54ef531c1ecd2be4389ad63c838376f221db13621a179ef5cf57a0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8e28c816cd54ef531c1ecd2be4389ad63c838376f221db13621a179ef5cf57a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8e28c816cd54ef531c1ecd2be4389ad63c838376f221db13621a179ef5cf57a0?s=96&d=mm&r=g","caption":"Joaquin"}}]}},"_links":{"self":[{"href":"https:\/\/vistiendobebes.com\/it\/wp-json\/wp\/v2\/posts\/67409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vistiendobebes.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vistiendobebes.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vistiendobebes.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vistiendobebes.com\/it\/wp-json\/wp\/v2\/comments?post=67409"}],"version-history":[{"count":0,"href":"https:\/\/vistiendobebes.com\/it\/wp-json\/wp\/v2\/posts\/67409\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vistiendobebes.com\/it\/wp-json\/wp\/v2\/media\/67417"}],"wp:attachment":[{"href":"https:\/\/vistiendobebes.com\/it\/wp-json\/wp\/v2\/media?parent=67409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vistiendobebes.com\/it\/wp-json\/wp\/v2\/categories?post=67409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vistiendobebes.com\/it\/wp-json\/wp\/v2\/tags?post=67409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}